{"id":519,"date":"2017-06-28T11:48:56","date_gmt":"2017-06-28T09:48:56","guid":{"rendered":"http:\/\/www.angerblick.at\/impressum\/"},"modified":"2022-09-06T10:43:09","modified_gmt":"2022-09-06T08:43:09","slug":"terms","status":"publish","type":"page","link":"https:\/\/www.angerblick.at\/en\/terms\/","title":{"rendered":"Terms"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1>Terms of use<\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881270686{margin-bottom: 25px !important;}&#8221;]<\/p>\n<h6>Website owner<\/h6>\n<p>[\/vc_column_text][vc_column_text]Familie Salzmann<\/p>\n<p>Anger 40<\/p>\n<p>A-5630 Bad Hofgastein<\/p>\n<p>Tel. <a href=\"tel:+436602008611\">+43 660 2008611<\/a><\/p>\n<p><a href=\"mailto:info@angerblick.at\">info@angerblick.at<\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881263236{margin-bottom: 25px !important;}&#8221;]<\/p>\n<h6>Authorities acc. to e-commerce laws<\/h6>\n<p>[\/vc_column_text][vc_column_text]Bezirkshauptmannschaft (District Council) in St. Johann im Pongau[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1500881325149{margin-bottom: 25px !important;}&#8221;]<\/p>\n<h6>Court of jurisdiction<\/h6>\n<p>[\/vc_column_text][vc_column_text]St. Johann im Pongau[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881310014{margin-bottom: 25px !important;}&#8221;]<\/p>\n<h6>Conzept, web design &amp; technical implementation<\/h6>\n<p>[\/vc_column_text][vc_column_text]IMPULS Werbeagentur OG<\/p>\n<p>Stadtplatz 11<\/p>\n<p>A-5550 Radstadt<\/p>\n<p><a href=\"http:\/\/www.impuls-werbeagentur.at\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.impuls-werbeagentur.at<\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1500881342518{margin-bottom: 25px !important;}&#8221;]<\/p>\n<h6>Photo credits<\/h6>\n<p>[\/vc_column_text][vc_column_text]Max Steinbauer Photography, Gasteinertal Tourismus, SalzburgerLand Tourismus, Shutterstock, privat[\/vc_column_text][vc_column_text]Diese Webseite wurde von der <a href=\"http:\/\/www.impuls-werbeagentur.at\/\" target=\"_blank\" rel=\"noopener noreferrer\">Full-Service Werbeagentur IMPULS<\/a> aus Radstadt im Pongau gestaltet, welche mit Leidenschaft erfolgreiche <a href=\"http:\/\/www.impuls-werbeagentur.at\/#leistungen\" target=\"_blank\" rel=\"noopener noreferrer\">Webauftritte<\/a> f\u00fcr Unternehmen in <a href=\"http:\/\/www.impuls-werbeagentur.at\/#agentur\" target=\"_blank\" rel=\"noopener noreferrer\">Tourismus<\/a>, <a href=\"http:\/\/www.impuls-werbeagentur.at\/#agentur\" target=\"_blank\" rel=\"noopener noreferrer\">Gastronomie<\/a>,<a href=\"http:\/\/www.impuls-werbeagentur.at\/#agentur\" target=\"_blank\" rel=\"noopener noreferrer\"> Handel &amp; Handwerk<\/a> kreiert und umsetzt. Weiters bietet IMPULS den Kunden <a href=\"http:\/\/www.impuls-werbeagentur.at\/#leistungen\" target=\"_blank\" rel=\"noopener noreferrer\">Printl\u00f6sungen<\/a> wie Gesch\u00e4ftsausstattungen, Inserate, Kataloge, Brosch\u00fcren und Flugbl\u00e4tter an. <a href=\"http:\/\/www.impuls-werbeagentur.at\/#leistungen\" target=\"_blank\" rel=\"noopener noreferrer\">Suchmaschinenoptimierung<\/a>, <a href=\"http:\/\/www.impuls-werbeagentur.at\/#leistungen\" target=\"_blank\" rel=\"noopener noreferrer\">Webshops<\/a>, <a href=\"http:\/\/www.impuls-werbeagentur.at\/#leistungen\" target=\"_blank\" rel=\"noopener noreferrer\">Social Marketing<\/a>, <a href=\"http:\/\/www.impuls-werbeagentur.at\/#leistungen\" target=\"_blank\" rel=\"noopener noreferrer\">Corporate Design<\/a> und <a href=\"http:\/\/www.impuls-werbeagentur.at\/#leistungen\" target=\"_blank\" rel=\"noopener noreferrer\">Outdoor Media<\/a> z\u00e4hlen ebenfalls zu den Kompetenzen der Werbeagentur im Pongau. Werfen Sie einen Blick in die <a href=\"http:\/\/www.impuls-werbeagentur.at\/websites\/\" target=\"_blank\" rel=\"noopener noreferrer\">Web-Referenzen<\/a>, <a href=\"http:\/\/www.impuls-werbeagentur.at\/drucksorten\/\" target=\"_blank\" rel=\"noopener noreferrer\">Druck-<\/a>und <a href=\"http:\/\/www.impuls-werbeagentur.at\/logos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Logo-Referenzen<\/a> und \u00fcberzeugen Sie sich von den Qualit\u00e4ten.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3>Haftungsausschluss<\/h3>\n<p>[\/vc_column_text][vc_column_text]<strong>Inhalt des Onlineangebotes<\/strong><\/p>\n<p>Der Autor \u00fcbernimmt keinerlei Gew\u00e4hr f\u00fcr die Aktualit\u00e4t, Korrektheit, Vollst\u00e4ndigkeit oder Qualit\u00e4t der bereitgestellten Informationen. Haftungsanspr\u00fcche gegen den Autor, welche sich auf Sch\u00e4den materieller oder ideeller Art beziehen, die durch die Nutzung oder Nichtnutzung der dargebotenen Informationen bzw. durch die Nutzung fehlerhafter und unvollst\u00e4ndiger Informationen verursacht wurden, sind grunds\u00e4tzlich ausgeschlossen, sofern seitens des Autors kein nachweislich vors\u00e4tzliches oder grob fahrl\u00e4ssiges Verschulden vorliegt. Alle Angebote sind freibleibend und unverbindlich. Der Autor beh\u00e4lt es sich ausdr\u00fccklich vor, Teile der Seiten oder das gesamte Angebot ohne gesonderte Ank\u00fcndigung zu ver\u00e4ndern, zu erg\u00e4nzen, zu l\u00f6schen oder die Ver\u00f6ffentlichung zeitweise oder endg\u00fcltig einzustellen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Verweise und Links<\/strong><\/p>\n<p>Bei direkten oder indirekten Verweisen auf fremde Internetseiten (\u201cLinks\u201d), die au\u00dferhalb des Verantwortungsbereiches des Autors liegen, w\u00fcrde eine Haftungsverpflichtung ausschlie\u00dflich in dem Fall in Kraft treten, in dem der Autor von den Inhalten Kenntnis hat und es ihm technisch m\u00f6glich und zumutbar w\u00e4re, die Nutzung im Falle rechtswidriger Inhalte zu verhindern.Der Autor erkl\u00e4rt hiermit ausdr\u00fccklich, dass zum Zeitpunkt der Linksetzung keine illegalen Inhalte auf den zu verlinkenden Seiten erkennbar waren. Auf die aktuelle und zuk\u00fcnftige Gestaltung, die Inhalte oder die Urheberschaft der gelinkten\/verkn\u00fcpften Seiten hat der Autor keinerlei Einfluss. Deshalb distanziert er sich hiermit ausdr\u00fccklich von allen Inhalten aller gelinkten \/verkn\u00fcpften Seiten, die nach der Linksetzung ver\u00e4ndert wurden. Diese Feststellung gilt f\u00fcr alle innerhalb des eigenen Internetangebotes gesetzten Links und Verweise sowie f\u00fcr Fremdeintr\u00e4ge in vom Autor eingerichteten G\u00e4steb\u00fcchern, Diskussionsforen und Mailinglisten. F\u00fcr illegale, fehlerhafte oder unvollst\u00e4ndige Inhalte und insbesondere f\u00fcr Sch\u00e4den, die aus der Nutzung oder Nichtnutzung solcherart dargebotener Informationen entstehen, haftet allein der Anbieter der Seite, auf welche verwiesen wurde, nicht derjenige, der \u00fcber Links auf die jeweilige Ver\u00f6ffentlichung lediglich verweist.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Urheber- und Kennzeichenrecht<\/strong><\/p>\n<p>Der Autor ist bestrebt, in allen Publikationen die Urheberrechte der verwendeten Grafiken, Tondokumente, Videosequenzen und Texte zu beachten, von ihm selbst erstellte Grafiken, Tondokumente, Videosequenzen und Texte zu nutzen oder auf lizenzfreie Grafiken, Tondokumente, Videosequenzen und Texte zur\u00fcckzugreifen. Alle innerhalb des Internetangebotes genannten und ggf. durch Dritte gesch\u00fctzten Marken- und Warenzeichen unterliegen uneingeschr\u00e4nkt den Bestimmungen des jeweils g\u00fcltigen Kennzeichenrechts und den Besitzrechten der jeweiligen eingetragenen Eigent\u00fcmer. Allein aufgrund der blo\u00dfen Nennung ist nicht der Schlu\u00df zu ziehen, dass Markenzeichen nicht durch Rechte Dritter gesch\u00fctzt sind! Das Copyright f\u00fcr ver\u00f6ffentlichte, vom Autor selbst erstellte Objekte bleibt allein beim Autor der Seiten. Eine Vervielf\u00e4ltigung oder Verwendung solcher Grafiken, Tondokumente, Videosequenzen und Texte in anderen elektronischen oder gedruckten Publikationen ist ohne ausdr\u00fcckliche Zustimmung des Autors nicht gestattet.<\/p>\n<p>&nbsp;<\/p>\n<p><strong id=\"datenschutz\">Datenschutzerkl\u00e4rung<\/strong><\/p>\n<p>Verantwortlich f\u00fcr die Verarbeitung Ihrer personenbezogenen Daten auf unserer Website ist Familie Salzmann, Anger 40, A-5630 Bad Hofgastein. Wir nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung. Ihre Daten werden ohne Ihre ausdr\u00fcckliche Zustimmung nicht an andere Empf\u00e4nger weitergegeben.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u201eTeilen\u201c-Buttons<\/strong><\/p>\n<p>Unsere Website verf\u00fcgt auf machen Seiten \u00fcber Buttons zum Teilen der Seiteninhalte auf den Social Media-Plattformen Facebook, Twitter, Google Plus, Pinterest. Die Buttons sind im Sinn des Schutzes der personenbezogenen Daten unserer Websitebesucher ideal ausgestaltet, da das hinter den Buttons liegende Skript (Computerprogramm) <strong>keine personenbezogenen Daten<\/strong> erfasst oder verarbeitet. Websitebesucher, die unsere Seite teilen wollen, werden bei Klick auf die Buttons direkt auf die \u201eTeilen\u201c-Seiten der jeweiligen Social Media-Plattformen geleitet. Erst dort werden die zum Teilen der Seiteninhalte notwendigen Skripte geladen. Dabei gelten dann die vom Websitebesucher mit den jeweiligen Social Media-Plattformen vereinbarten Gesch\u00e4fts- und Datenschutzbedingungen. Genaue Informationen dar\u00fcber bieten die jeweiligen Plattformen <a href=\"https:\/\/www.facebook.com\/policy.php\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>, <a href=\"https:\/\/www.google.com\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">Google Plus<\/a>, <a href=\"https:\/\/help.twitter.com\/de\/rules-and-policies\/twitter-rules\" target=\"_blank\" rel=\"noopener\">Twitter<\/a>, <a href=\"https:\/\/policy.pinterest.com\/en\" target=\"_blank\" rel=\"noopener\">Pinterest<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Cookies<\/strong><\/p>\n<p>Diese Website verwendet Cookies. Cookies machen Websites f\u00fcr den Benutzer benutzerfreundlicher und effizienter. Ein Cookie ist eine kleine Textdatei, die zur Speicherung von Informationen dient. Beim Besuch einer Website kann die Website auf dem Computer des Website-Besuchers ein Cookie platzieren. Besucht der Benutzer die Website sp\u00e4ter wieder, kann die Website die Daten des fr\u00fcher gespeicherten Cookies auslesen und so z.B. feststellen, ob der Benutzer die Website schon fr\u00fcher besucht hat und f\u00fcr welche Bereiche der Website sich der Benutzer besonders interessiert hat. Mehr Informationen zu Cookies erhalten Sie auf <a href=\"http:\/\/de.wikipedia.org\/wiki\/HTTP-Cookie\" target=\"_blank\" rel=\"noopener\">WIKIPEDIA<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00c4ndern der Cookie-Einstellungen<\/strong><br \/>\nWie der Web-Browser mit Cookies umgeht, welche Cookies zugelassen oder abgelehnt werden, kann der Benutzer in den Einstellungen des Web-Browsers festlegen. Wo genau sich diese Einstellungen befinden, h\u00e4ngt vom jeweiligen Web-Browser ab. Detailinformationen dazu k\u00f6nnen \u00fcber die Hilfe-Funktion des jeweiligen Web-Browsers aufgerufen werden. Wenn die Nutzung von Cookies eingeschr\u00e4nkt wird, sind unter Umst\u00e4nden nicht mehr alle Funktionen dieser Website vollumf\u00e4nglich nutzbar.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Cookies auf unserer Website<\/strong><br \/>\nUnsere Website verwendet folgende Anbieter:<br \/>\nMatomo<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ihre Rechte<\/strong><\/p>\n<p>Sie haben das Recht auf Auskunft, Berichtigung, L\u00f6schung und Einschr\u00e4nkung der Verarbeitung der personenbezogenen Daten sowie das Recht auf Daten\u00fcbertragbarkeit. Sie haben das Recht auf Widerruf eventuell erteilter Einwilligungen zur Verarbeitung Ihrer personenbezogenen Daten. Die Rechtm\u00e4\u00dfigkeit der Verarbeitung der personenbezogenen Daten bis zum Widerruf wird durch den Widerruf nicht ber\u00fchrt. Sie haben das Recht auf Widerspruch gegen die Verarbeitung Ihrer personenbezogenen Daten zum Zweck der Direktwerbung. Im Fall des Widerspruchs werden Ihre personenbezogenen Daten nicht mehr zum Zwecke der Direktwerbung verarbeitet. Weiters haben Sie das Recht auf Beschwerde bei der Aufsichtsbeh\u00f6rde (\u00d6sterreichische Datenschutzbeh\u00f6rde, Wickenburggasse 8, 1080 Wien, dsb@dsb.gv.at).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Rechtswirksamkeit dieses Haftungsausschlusses<\/strong><\/p>\n<p>Dieser Haftungsausschluss ist als Teil des Internetangebotes zu betrachten, von dem aus auf diese Seite verwiesen wurde. Sofern Teile oder einzelne Formulierungen dieses Textes der geltenden Rechtslage nicht, nicht mehr oder nicht vollst\u00e4ndig entsprechen sollten, bleiben die \u00fcbrigen Teile des Dokumentes in ihrem Inhalt und ihrer G\u00fcltigkeit davon unber\u00fchrt.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>W3C<\/strong><\/p>\n<p>Diese Homepage entspricht den Richtlinien der W3C.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Terms of use [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881270686{margin-bottom: 25px !important;}&#8221;] Website owner [\/vc_column_text][vc_column_text]Familie Salzmann Anger 40 A-5630 Bad Hofgastein Tel. +43 660 2008611 info@angerblick.at[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881263236{margin-bottom: 25px !important;}&#8221;] Authorities acc. to e-commerce laws [\/vc_column_text][vc_column_text]Bezirkshauptmannschaft (District Council) in St. Johann im Pongau[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1500881325149{margin-bottom: 25px !important;}&#8221;] Court of jurisdiction [\/vc_column_text][vc_column_text]St. Johann im Pongau[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881310014{margin-bottom: 25px !important;}&#8221;] Conzept, &hellip;<\/p>\n\n<p><a class=\"readmore btn btn-default btn-default btn-block\" href=\"https:\/\/www.angerblick.at\/en\/terms\/\">Read More<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-519","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terms - Angerblick<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.angerblick.at\/impressum\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms - Angerblick\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] Terms of use [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881270686{margin-bottom: 25px !important;}&#8221;] Website owner [\/vc_column_text][vc_column_text]Familie Salzmann Anger 40 A-5630 Bad Hofgastein Tel. +43 660 2008611 info@angerblick.at[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881263236{margin-bottom: 25px !important;}&#8221;] Authorities acc. to e-commerce laws [\/vc_column_text][vc_column_text]Bezirkshauptmannschaft (District Council) in St. Johann im Pongau[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1500881325149{margin-bottom: 25px !important;}&#8221;] Court of jurisdiction [\/vc_column_text][vc_column_text]St. Johann im Pongau[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881310014{margin-bottom: 25px !important;}&#8221;] Conzept, &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.angerblick.at\/impressum\/\" \/>\n<meta property=\"og:site_name\" content=\"Angerblick\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-06T08:43:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.angerblick.at\\\/impressum\\\/\",\"url\":\"https:\\\/\\\/www.angerblick.at\\\/impressum\\\/\",\"name\":\"Terms - Angerblick\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.angerblick.at\\\/en\\\/#website\"},\"datePublished\":\"2017-06-28T09:48:56+00:00\",\"dateModified\":\"2022-09-06T08:43:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.angerblick.at\\\/impressum\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.angerblick.at\\\/impressum\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.angerblick.at\\\/impressum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.angerblick.at\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.angerblick.at\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.angerblick.at\\\/en\\\/\",\"name\":\"Angerblick\",\"description\":\"Skih\u00fctte &amp; Apr\u00e8s Ski in Bad Hofgastein\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.angerblick.at\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terms - Angerblick","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.angerblick.at\/impressum\/","og_locale":"en_US","og_type":"article","og_title":"Terms - Angerblick","og_description":"[vc_row][vc_column][vc_column_text] Terms of use [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881270686{margin-bottom: 25px !important;}&#8221;] Website owner [\/vc_column_text][vc_column_text]Familie Salzmann Anger 40 A-5630 Bad Hofgastein Tel. +43 660 2008611 info@angerblick.at[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881263236{margin-bottom: 25px !important;}&#8221;] Authorities acc. to e-commerce laws [\/vc_column_text][vc_column_text]Bezirkshauptmannschaft (District Council) in St. Johann im Pongau[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1500881325149{margin-bottom: 25px !important;}&#8221;] Court of jurisdiction [\/vc_column_text][vc_column_text]St. Johann im Pongau[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1500881310014{margin-bottom: 25px !important;}&#8221;] Conzept, &hellip;","og_url":"https:\/\/www.angerblick.at\/impressum\/","og_site_name":"Angerblick","article_modified_time":"2022-09-06T08:43:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.angerblick.at\/impressum\/","url":"https:\/\/www.angerblick.at\/impressum\/","name":"Terms - Angerblick","isPartOf":{"@id":"https:\/\/www.angerblick.at\/en\/#website"},"datePublished":"2017-06-28T09:48:56+00:00","dateModified":"2022-09-06T08:43:09+00:00","breadcrumb":{"@id":"https:\/\/www.angerblick.at\/impressum\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.angerblick.at\/impressum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.angerblick.at\/impressum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.angerblick.at\/en\/"},{"@type":"ListItem","position":2,"name":"Terms"}]},{"@type":"WebSite","@id":"https:\/\/www.angerblick.at\/en\/#website","url":"https:\/\/www.angerblick.at\/en\/","name":"Angerblick","description":"Skih\u00fctte &amp; Apr\u00e8s Ski in Bad Hofgastein","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.angerblick.at\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.angerblick.at\/en\/wp-json\/wp\/v2\/pages\/519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.angerblick.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.angerblick.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.angerblick.at\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.angerblick.at\/en\/wp-json\/wp\/v2\/comments?post=519"}],"version-history":[{"count":5,"href":"https:\/\/www.angerblick.at\/en\/wp-json\/wp\/v2\/pages\/519\/revisions"}],"predecessor-version":[{"id":686,"href":"https:\/\/www.angerblick.at\/en\/wp-json\/wp\/v2\/pages\/519\/revisions\/686"}],"wp:attachment":[{"href":"https:\/\/www.angerblick.at\/en\/wp-json\/wp\/v2\/media?parent=519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}